{"id":2043,"date":"2016-03-17T10:18:38","date_gmt":"2016-03-17T09:18:38","guid":{"rendered":"http:\/\/blogs.univ-jfc.fr\/campsdusudouest\/?page_id=2043"},"modified":"2016-03-31T09:17:55","modified_gmt":"2016-03-31T08:17:55","slug":"la-propagande-mediatique-sous-le-gouvernement-de-daladier-et-du-regime-de-vichy-de-1938-a-1945","status":"publish","type":"page","link":"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/la-france-de-lentre-deux-guerres-et-de-vichy\/les-francais-et-linternement\/la-propagande-mediatique-sous-le-gouvernement-de-daladier-et-du-regime-de-vichy-de-1938-a-1945\/","title":{"rendered":"La propagande m\u00e9diatique sous le gouvernement de Daladier et du r\u00e9gime de Vichy, de 1938 \u00e0 1945"},"content":{"rendered":"<address><a href=\"http:\/\/blogs.univ-jfc.fr\/campsdusudouest\/la-france-de-lentre-deux-guerres-et-de-vichy\/les-francais-et-linternement\/\" target=\"_blank\">&#8230; page pr\u00e9c\u00e9dente<\/a><\/address>\n<address><strong><span style=\"font-family: Arial,serif\"><span style=\"font-size: large\">La propagande m\u00e9diatique sous le gouvernement de Daladier et le r\u00e9gime de Vichy, de 1938 \u00e0 1945<\/span><\/span><\/strong><\/address>\n<p align=\"justify\"><a name=\"__RefHeading___Toc2260_1991510388\"><\/a> <em><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">Une presse Fran\u00e7aise d\u00e9chir\u00e9e sur l&rsquo;internement des immigr\u00e9s Espagnols en 1939<\/span><\/span><\/em><\/p>\n<div id=\"attachment_2837\" style=\"width: 194px\" class=\"wp-caption alignright\"><a href=\"http:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/03\/larriv\u00e9e.jpg\"><img aria-describedby=\"caption-attachment-2837\" loading=\"lazy\" class=\"size-medium wp-image-2837 \" title=\"Le Populaire du dimanche 29 janvier 1939. Source : Le 24 ao\u00fbt 1944 ( http:\/\/www.24-aout-1944.org\/L-exode-republicain-espagnol-de)\" alt=\"l'arriv\u00e9e\" src=\"http:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/03\/larriv\u00e9e-184x300.jpg\" width=\"184\" height=\"300\" srcset=\"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/03\/larriv\u00e9e-184x300.jpg 184w, https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/03\/larriv\u00e9e.jpg 262w\" sizes=\"(max-width: 184px) 100vw, 184px\" \/><\/a><p id=\"caption-attachment-2837\" class=\"wp-caption-text\">L\u2019arriv\u00e9e des immigr\u00e9s Espagnol<\/p><\/div>\n<p align=\"justify\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\"> La presse fran\u00e7aise commence \u00e0 parler des r\u00e9publicains espagnols bien avant l&rsquo;ouverture des camps. D\u00e8s le commencement de la guerre civile en 1936, la presse s\u2019enflamme pour ce sujet et se retrouve divis\u00e9e sur fond de x\u00e9nophobie sur la r\u00e9publique espagnole. Cette violence verbale se d\u00e9clenche apr\u00e8s un conseil des ministres cens\u00e9 se prononcer sur la demande d&rsquo;aide formul\u00e9 par le pr\u00e9sident du conseil espagnol Jos\u00e9 Giral<a href=\"#sdfootnote1sym\" name=\"sdfootnote1anc\"><sup>1<\/sup><\/a> aupr\u00e8s de L\u00e9on Blum<a href=\"#sdfootnote2sym\" name=\"sdfootnote2anc\"><sup>2<\/sup><\/a>. La r\u00e9ponse d&rsquo;abord positive de L\u00e9on Blum d\u00e9clenche une virulente r\u00e9ponse des journaux de droite. Le journal patriotique et conservateur,\u00a0<i><b>L\u2019\u00c9cho de Paris<\/b><\/i>, connu pour son opposition envers l&rsquo;immigration titre le 25 juillet 1936, \u00ab\u00a0les avions fran\u00e7ais livr\u00e9s par M. Pierre Cot<a href=\"#sdfootnote3sym\" name=\"sdfootnote3anc\"><sup>3<\/sup><\/a> vont- ils partir pour Barcelone\u00a0\u00bb<a href=\"#sdfootnote4sym\" name=\"sdfootnote4anc\"><sup>4<\/sup><\/a>. Dans cet article le gouvernement fran\u00e7ais est accus\u00e9 de vouloir aider \u00ab\u00a0une capitale tomb\u00e9e au main d&rsquo;un soviet communo-anarchiste, d\u00e9cor\u00e9 du nom de comit\u00e9 du salut public\u00a0\u00bb<a href=\"#sdfootnote5sym\" name=\"sdfootnote5anc\"><sup>5<\/sup><\/a>, <i><b>Le Figaro<\/b><\/i> dans son num\u00e9ro du 25 juillet accuse aussi le gouvernement d\u2019intervenir dans cette guerre en toute ill\u00e9gitimit\u00e9.<span style=\"color: #333344\">\u00a0<\/span><span style=\"color: #000000\">De l&rsquo;autre c\u00f4t\u00e9, la presse de gauche tels que <\/span><span style=\"color: #000000\"><i><b>Le Populaire<\/b><\/i><\/span><span style=\"color: #000000\">, <\/span><span style=\"color: #000000\"><i><b>L\u2019\u0152uvre<\/b><\/i><\/span><span style=\"color: #000000\"> ou <\/span><span style=\"color: #000000\"><i><b>L&rsquo;Humanit\u00e9<\/b><\/i><\/span><span style=\"color: #000000\">\u00a0d\u00e9fendent les r\u00e9publicains espagnols. Autant dire que la presse fran\u00e7aise est divis\u00e9e et cela ne va pas s&rsquo;arranger avec la prise de Barcelone et l&rsquo;arriv\u00e9e en masse de quelques 500 000 espagnols \u00e0 la fronti\u00e8re. <\/span><\/span><\/span><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\"><span style=\"color: #000000\">Cette fois le d\u00e9bat oppose ce qui veulent accueillir dignement ces combattants antifascistes <\/span><span style=\"color: #000000\">et ceux qui s&rsquo;insurge<\/span><span style=\"color: #000000\">nt<\/span><span style=\"color: #000000\"> sur <\/span><span style=\"color: #000000\">d<\/span><span style=\"color: #000000\">es conditions <\/span><span style=\"color: #000000\">dans lesquelles sont<\/span><span style=\"color: #000000\"> accueil<\/span><span style=\"color: #000000\">li<\/span><span style=\"color: #000000\">s <\/span><span style=\"color: #000000\">l<\/span><span style=\"color: #000000\">es r\u00e9fugi\u00e9s comme <\/span><span style=\"color: #000000\"><i><b>L\u2019\u00c9cho de Paris<a href=\"#sdfootnote6sym\" name=\"sdfootnote6anc\"><sup>6<\/sup><\/a><\/b><\/i><\/span><span style=\"color: #000000\"> qui s\u2019inqui\u00e8te de voir la France envahie par cette immigration massive. La presse favorable \u00e0 l&rsquo;arriv\u00e9e des r\u00e9publicains s&rsquo;appuie sur l&rsquo;id\u00e9ologie d&rsquo;une France \u00ab\u00a0terre d&rsquo;asile\u00a0\u00bb et demande aux autorit\u00e9s d&rsquo;installer dans des conditions dignes les femmes, les enfants, les bless\u00e9s de guerre et les vieillards. C<\/span><span style=\"color: #000000\">&lsquo;<\/span><span style=\"color: #000000\">e<\/span><span style=\"color: #000000\">s<\/span><span style=\"color: #000000\">t d&rsquo;ailleurs sur ces sc\u00e8nes de d\u00e9solations que vont jouer ces journaux. Ainsi <\/span><span style=\"color: #000000\"><i><b>Le Populaire<\/b><\/i><\/span><span style=\"color: #000000\"> du 29 janvier 1939 titre \u00ab\u00a0La France, supr\u00eame espoir des femmes et enfants d&rsquo;espagnols qui fuient la mitraille des barbares\u00a0\u00bb<a href=\"#sdfootnote7sym\" name=\"sdfootnote7anc\"><sup>7<\/sup><\/a>, avec une photo de femmes et d&rsquo;enfants d\u00e9s\u0153uvr\u00e9s \u00e0 la fronti\u00e8re. Il s&rsquo;agit d&rsquo;ajouter aux enjeux politiques et id\u00e9ologiques un facteur humain appuy\u00e9 par la presse par de nombreuse photos d&rsquo;hommes et d&rsquo;enfants bless\u00e9s comme le fait <\/span><span style=\"color: #000000\"><i><b>Ce Soir<\/b><\/i><\/span><span style=\"color: #000000\"> qui chaque jour y co<\/span><\/span><\/span><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\"><span style=\"color: #000000\">nsacre une rubrique enti\u00e8re.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #000000\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">Mais l&rsquo;autre bastion de cette presse de gauche est l&rsquo;ouverture des camps d&rsquo;internements et plus particuli\u00e8rement les conditions d&rsquo;internements des civils espagnols.<i><b>Le Midi socialiste<\/b><\/i> du 19 f\u00e9vrier 1939<a href=\"#sdfootnote8sym\" name=\"sdfootnote8anc\"><sup>8<\/sup><\/a> nous apprend beaucoup sur la d\u00e9tention dans les camps d&rsquo;Argel\u00e8s avec sa publication du rapport de la d\u00e9l\u00e9gation du groupe socialiste. Ce qui nous permet d&rsquo;avoir une description du camp ainsi que de son fonctionnement. Nous savons que cette d\u00e9l\u00e9gation a visit\u00e9 les camps d&rsquo;Argel\u00e8s et St Cyprien les 9 et 14 f\u00e9vrier 1939. Le rapport qu&rsquo;elle en fait d\u00e9crit un chaos sans nom. Il r\u00e8gne dans le camp \u00ab\u00a0un d\u00e9sordre g\u00e9n\u00e9ral\u00a0\u00bb o\u00f9 sont mont\u00e9 \u00e0 la va vite quelques baraquements et puits autour desquels s&rsquo;entassent 72 000 hommes pour St Cyprien et 65 000 pour Argel\u00e8s<a href=\"#sdfootnote9sym\" name=\"sdfootnote9anc\"><sup>9<\/sup><\/a>. Ces camps au bord de la mer sont entour\u00e9s de barbel\u00e9s. Les hommes, les femmes, les vieillards et des gamins sont m\u00e9lang\u00e9s aux miliciens dans une dangereuse promiscuit\u00e9. \u00c0 cela s&rsquo;ajoute la faim due \u00e0 une mauvaise organisations des autorit\u00e9s qui g\u00e8rent le camp et le froid malm\u00e8ne des corps d\u00e9j\u00e0 affaiblis. D&rsquo;ailleurs des morts sont \u00e0 d\u00e9plorer dans les camps. Outre ces conditions de vies tr\u00e8s dures, les intern\u00e9s ont \u00e9t\u00e9 victimes d&rsquo;abus, on leur a confisqu\u00e9 des appareils photos, des briquets et des objets divers qui n&rsquo;ont rien \u00e0 voir avec le mat\u00e9riel militaire qui devait normalement \u00eatre confisqu\u00e9. De plus des hauts parleurs diffusent devant la partie des camps r\u00e9serv\u00e9s aux brigades internationales des messages de propagande franquiste. La d\u00e9l\u00e9gation se d\u00e9sole aussi de la mauvaise administration et du manque de collaboration entre les autorit\u00e9s fran\u00e7aises et espagnoles. Ce qui explique aussi qu&rsquo; aucune fiche individuelle de renseignement ont \u00e9t\u00e9 remplis, ce qui rend les familles \u00e9clat\u00e9es dans les diff\u00e9rents camps dures \u00e0 rassembler.<\/span><\/span><\/span><\/p>\n<div id=\"attachment_1856\" style=\"width: 310px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/01\/4.jpg\"><img aria-describedby=\"caption-attachment-1856\" loading=\"lazy\" class=\"size-medium wp-image-1856 \" title=\"Dessins des camps de Joseph Bartoli (1910-1995) intern\u00e9 au camps de Bram, en 1939. Source\u00a0: Bartoli G. Garcia L. , La\u00a0Retirada\u00a0: exode et exil des r\u00e9publicains d'Espagne, Acte sud, 2009, p 83-84.\" alt=\"4\" src=\"http:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/01\/4-300x277.jpg\" width=\"300\" height=\"277\" srcset=\"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/01\/4-300x277.jpg 300w, https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/01\/4-1024x945.jpg 1024w, https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/01\/4-324x300.jpg 324w, https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/01\/4.jpg 1312w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-1856\" class=\"wp-caption-text\">Camps de Bram<\/p><\/div>\n<div id=\"attachment_3119\" style=\"width: 275px\" class=\"wp-caption alignright\"><a href=\"http:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/03\/le-populaire.jpg\"><img aria-describedby=\"caption-attachment-3119\" loading=\"lazy\" class=\"size-medium wp-image-3119 \" title=\"T\u00e9moignage d'un journaliste de gauche sur les conditions de vie dans les camps. Source\u00a0: http:\/\/gallica.bnf.fr\/ark:\/12148\/bpt6k823313b.item\" alt=\"le populaire\" src=\"http:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/03\/le-populaire-265x300.jpg\" width=\"265\" height=\"300\" srcset=\"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/03\/le-populaire-265x300.jpg 265w, https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-content\/uploads\/sites\/48\/2016\/03\/le-populaire.jpg 502w\" sizes=\"(max-width: 265px) 100vw, 265px\" \/><\/a><p id=\"caption-attachment-3119\" class=\"wp-caption-text\">Journal Le Populaire<\/p><\/div>\n<p align=\"justify\"><span style=\"color: #000000\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\"><i><b>L&rsquo;Humanit\u00e9<\/b><\/i>, journal du parti communiste va aussi s&rsquo;indigner sur les camps d&rsquo;internements en mettant en avant le manque de m\u00e9dicaments et de services m\u00e9dicaux. Le 15 f\u00e9vrier les camps sont d\u00e9peints comme \u00ab\u00a0un v\u00e9ritable p\u00e9nitencier ou couve un foyer d&rsquo;\u00e9pid\u00e9mies\u00a0\u00bb<a href=\"#sdfootnote10sym\" name=\"sdfootnote10anc\"><sup>10<\/sup><\/a>. <i><b>Ce soir<\/b><\/i>, commence a s\u2019int\u00e9resser au camp d&rsquo;internement \u00e0 partir du 12 f\u00e9vrier. Son envoy\u00e9 sp\u00e9cial St\u00e9phane Manier \u00e9crit\u00a0\u00ab\u00a0<i>\u00c0 Argel\u00e8s sur mer, ce n\u2019est plus la mitraille qui tue, c\u2019est la faim, la fi\u00e8vre, le froid\u00a0<\/i>\u00a0\u00bb<a href=\"#sdfootnote11sym\" name=\"sdfootnote11anc\"><sup>11<\/sup><\/a>. <\/span><\/span><\/span><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\"><span style=\"color: #000000\">Le journal <\/span><span style=\"color: #000000\"><i><b>Le Populaire<\/b><\/i><\/span><span style=\"color: #000000\"> du 13 f\u00e9vrier 1939 fait les m\u00eames contestations. Ces faits ( ci-dessous) ont \u00e9t\u00e9 rapport\u00e9<\/span><span style=\"color: #000000\">s<\/span><span style=\"color: #000000\"> par un envoy\u00e9 sp\u00e9cial, Jean-Maurice Herrman. Ce qui prouve que les journalistes de gauche ont le droit d&rsquo;entrer dans les camps jusqu&rsquo;\u00e0 mi f\u00e9vrier. Cependant, le 24 f\u00e9vrier 1939, <\/span><span style=\"color: #000000\"><i><b>Le Midi Socialiste<\/b><\/i><\/span><span style=\"color: #000000\"> \u00e9dite un article apr\u00e8s avoir \u00e9t\u00e9 interdit avec un autre journal, <\/span><span style=\"color: #000000\"><i><b>Le Populaire <\/b><\/i><\/span><span style=\"color: #000000\">d&rsquo;entrer dans les camps <\/span><span style=\"color: #000000\"><i><b>. <\/b><\/i><\/span><span style=\"color: #000000\">Les deux journaux de gauches\u00a0<\/span><span style=\"color: #000000\">qui <\/span><span style=\"color: #000000\">d\u00e9noncent les traitements que subissent les r\u00e9publicains espagnols sur les camps d\u2019Argel\u00e8s et de Saint-Cyprien sont devenus g\u00eanant pour les autorit\u00e9s. Il a donc \u00e9t\u00e9 d\u00e9cid\u00e9 de fermer d\u00e9s la fin de f\u00e9vrier les portes des camps \u00e0 la presse d&rsquo;opposition. C&rsquo;est le d\u00e9but de la censure de la presse, les autorit\u00e9s doivent \u00e9viter la divulgation au grand public des v\u00e9ritables conditions de vie des r\u00e9fugi\u00e9s.<br \/>\n<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #000000\"> <span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">Par contre la presse de droite \u00ab\u00a0celle qui couvre d&rsquo;injure les r\u00e9publicains espagnols\u00a0\u00bb<a href=\"#sdfootnote12sym\" name=\"sdfootnote12anc\"><sup>12<\/sup><\/a><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Arial,serif\"> est, elle, <span style=\"color: #000000\">d&rsquo;apr\u00e8s le journal toujours autoris\u00e9e a visiter les camps. Cette anecdote d\u00e9montre bien que le gouvernement fran\u00e7ais utilise la presse comme propagande. Malgr\u00e9 ces incidents, la presse de <\/span><span style=\"color: #000000\">gauche va n&rsquo;avoir de cesse d&rsquo;alerter l&rsquo;opinion publique et les autorit\u00e9s sur les camps pendant tout le mois de f\u00e9vrier et de mani\u00e8re encore plus insistante au fur et \u00e0 mesure que les conditions <\/span><span style=\"color: #000000\">d&rsquo;internements se d\u00e9gradent. <\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\"><span style=\"color: #000000\">La presse d&rsquo;extr\u00eame droite <\/span><span style=\"color: #000000\"><i><b>Le Matin, Le Jour <\/b><\/i><\/span><span style=\"color: #000000\">et<\/span><span style=\"color: #000000\"><i><b> Candide <\/b><\/i><\/span><span style=\"color: #000000\">ne voit pas cette arriv\u00e9e massive du m\u00eame \u0153il. Pour eux, il est essentiel que les espagnols repartent chez eux au plus vite. Il s&rsquo;agit d&rsquo;inqui\u00e9ter la population fran\u00e7aise avec des titres aussi alarmants que \u00ab\u00a0<\/span><span style=\"color: #000000\"><i>L\u2019inqui\u00e9tude vient des camps de concentration\u00a0<a href=\"#sdfootnote13sym\" name=\"sdfootnote13anc\"><sup>13<\/sup><\/a><\/i><\/span>\u00a0<span style=\"color: #000000\">\u00a0\u00bb, par le journal <\/span><span style=\"color: #000000\"><i><b>L\u2019\u00c9poque<\/b><\/i><\/span><span style=\"color: #000000\">.\u00a0Ou encore <\/span><span style=\"color: #000000\"><i><b>Candide <\/b><\/i><\/span><span style=\"color: #000000\">dit des miliciens espagnols \u00ab\u00a0<\/span><span style=\"color: #000000\"><i>Ils ne se soucient pas d\u2019affronter l\u2019arm\u00e9e de Franco, et pr\u00e9f\u00e8rent la vie dans un camp de concentration fran\u00e7ais. On les re\u00e7oit, on les h\u00e9berge tant bien que mal, \u00e0 Argel\u00e8s, au Boulou, \u00e0 Fort les Bains. On leur donne \u00e0 manger\u00a0<a href=\"#sdfootnote14sym\" name=\"sdfootnote14anc\"><sup>14<\/sup><\/a><\/i><\/span><span style=\"color: #000000\">\u00a0\u00bb. <\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">Pour cette presse le but n&rsquo;est plus de d\u00e9crire le camp ou les conditions de vies des intern\u00e9s mais de les diaboliser afin d&rsquo;inqui\u00e9ter les fran\u00e7ais. <\/span><\/span><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">Cette couverture m\u00e9diatique sur les camps va petit \u00e0 petit s&rsquo;\u00e9teindre avec l\u2019arriv\u00e9e des troupes allemandes et la Seconde Guerre mondiale mais elle nous permet d&rsquo;avoir une description des camps et de leurs fonctionnements ainsi que la vision d&rsquo;une France gangren\u00e9e par la x\u00e9nophobie.<\/span><\/span><\/span><\/p>\n<p align=\"justify\">\n<p align=\"justify\"><em>La censure m\u00e9diatique sous Vichy de 1940 \u00e0 1945<\/em><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\"> <span style=\"color: #111111\"> Le r\u00e9gime de Vichy est officiellement instaur\u00e9 en France le 10 juillet 1940, lorsque l&rsquo;Assembl\u00e9e nationale c\u00e8de les pleins pouvoirs au mar\u00e9chal Philippe P\u00e9tain. Il s&rsquo;autoproclame alors \u00ab chef de l\u2019\u00c9tat fran\u00e7ais \u00bb et poursuit une politique de collaboration, d\u00e9j\u00e0 entam\u00e9e quelques semaines auparavant, avec l&rsquo;Allemagne nazie. Suite \u00e0 ce changement, une propagande \u00e0 l&rsquo;encontre des opposants aux r\u00e9gimes fascistes est mise en place. Le gouvernement de Vichy accentue les mesures de censure m\u00e9diatique concernant les camps de \u00abconcentration\u00bb fran\u00e7ais conform\u00e9ment aux directives allemandes. La presse fran\u00e7aise se retrouve alors r\u00e9duite au silence, ce qui att\u00e9nue fortement les informations d\u00e9j\u00e0 tr\u00e8s minimes que poss\u00e8dent les Fran\u00e7ais sur les camps.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #000000\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">En d\u00e9pit de l&rsquo;effort gouvernemental d&rsquo;organiser et de contr\u00f4ler une presse d\u00e9sormais collaborationniste vou\u00e9e \u00e0 taire la situation des camps d&rsquo;internements, une campagne de presse internationale prend peu \u00e0 peu de l&rsquo;ampleur. Elle provient pour l&rsquo;essentiel d&rsquo;associations humanitaires telles que la Croix-Rouge et de la presse suisse et am\u00e9ricaine qui cherchent \u00e0 d\u00e9noncer les conditions d&rsquo;internements d\u00e9plorables en France.<\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">A titre d&rsquo;exemple, le quotidien suisse <i><b>Basler Nachriten<\/b><\/i> publie le 8 octobre 1940 un article \u00e9voquant la situation du camp d&rsquo;internement de Saint-Cyprien. Cette publication entra\u00eene une vive r\u00e9action de la part du gouvernement de P\u00e9tain. En effet la direction du journal a re\u00e7u une protestation de la part du minist\u00e8re de l&rsquo;Int\u00e9rieur fran\u00e7ais, assortie de faux t\u00e9moignages d&rsquo;intern\u00e9s \u00e0 l&rsquo;appuie.<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">Par la suite, avec la mont\u00e9e grandissante des protestations \u00e0 l&rsquo;\u00e9tranger et devant son \u00e9chec \u00e0 contr\u00f4ler totalement l&rsquo;information, le gouvernement de Vichy va recourir \u00e0 de nombreux subterfuges bureaucratiques, renvoyant les demandes de visites des camps en provenance de l&rsquo;\u00e9tranger entre d\u00e9partements minist\u00e9riels. Cette man\u0153uvre a pour but d&rsquo;endiguer l&rsquo;indignation que suscite la gestion anarchique des camps. <\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">On annonce dans le journal <i><b>Avenir<\/b><\/i> du 6 f\u00e9vrier 1941 que le gouvernement d\u00e9cide de la r\u00e9organisation compl\u00e8te du service des camps sous l&rsquo;initiative du docteur Limousin<a href=\"#sdfootnote15sym\" name=\"sdfootnote15anc\"><sup>15<\/sup><\/a>, ce qui eut pour cons\u00e9quence une nouvelle r\u00e9partition des \u00e9trangers dans les camps. L&rsquo;objectif est de simuler un contr\u00f4le sur la question de l&rsquo;internement et de ne pas diviser l&rsquo;opinion.<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">N\u00e9anmoins au niveau national, une presse interne clandestine a bel et bien subsist\u00e9. L&rsquo;on peut citer les quotidiens de propagande communistes tel que <i><b>l&rsquo;Humanit\u00e9<\/b><\/i> ou <i><b>Ce Soir<\/b><\/i><i> <\/i>qui furent saisies d\u00e8s le 25 ao\u00fbt 1939 sous l&rsquo;initiative du gouvernement. Ult\u00e9rieurement, la circulation des journaux clandestins permit aux groupuscules communistes de s&rsquo;organiser et de susciter une indignation somme toute relative aupr\u00e8s de l&rsquo;opinion. Le PCF<a href=\"#sdfootnote16sym\" name=\"sdfootnote16anc\"><sup>16<\/sup><\/a> s&rsquo;engage dans une lutte arm\u00e9e contre le r\u00e9gime de Vichy d\u00e8s l&rsquo;\u00e9t\u00e9 1941, ce qui aboutit \u00e0 une vague d&rsquo;attentats dans le Nord de la France. Le journal communiste du Nord <i><b>l&rsquo;Encha\u00een\u00e9<\/b><\/i> refuse de revendiquer les attentats et les attribue aux soldats allemands afin de gagner les faveurs de l&rsquo;opinion publique. Ce n&rsquo;est qu&rsquo;en d\u00e9cembre 1941 que le PCF assume ses actions \u00e0 travers les lignes du journal <i><b>l&rsquo;Humanit\u00e9<\/b><\/i><i>, <\/i>pr\u00e9sentant leurs actes comme l\u00e9gitimes, en r\u00e9ponse \u00e0 l\u2019ex\u00e9cution d&rsquo;otages communistes sur ordre du gouvernement.<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">De plus en plus soucieux de l&rsquo;image qu&rsquo;il renvoie aupr\u00e8s de ses citoyens, le r\u00e9gime de Vichy dispose de ses forces de police et de son administration pr\u00e9fectorale pour suivre l&rsquo;\u00e9tat de l&rsquo;opinion. Entre 1941 et 1942, il renforce sa politique de censure avec notamment un contr\u00f4le accru du courrier par voie postale. Le gouvernement esp\u00e8re ainsi \u00e9viter que les t\u00e9moignages concernant les internements ainsi que la mobilisation des moyens humains et mat\u00e9riels consacr\u00e9s aux premi\u00e8res rafles et d\u00e9portations ne s&rsquo;\u00e9bruitent.<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">Jusqu&rsquo;\u00e0 l&rsquo;\u00e9t\u00e9 1942, les mesures prises \u00e0 l&rsquo;encontre des Juifs ainsi que des intern\u00e9s suscitent une indiff\u00e9rence quasi g\u00e9n\u00e9rale aupr\u00e8s des fran\u00e7ais, martel\u00e9s par la propagande nazie qui s\u00e9vit au sein de la soci\u00e9t\u00e9. Cependant la tendance s&rsquo;inverse entre juillet et septembre 1942. De nombreux rapports administratifs \u00e0 l&rsquo;attention du minist\u00e8re de l&rsquo;Int\u00e9rieur indiquent que les fran\u00e7ais sont de plus en plus d\u00e9concert\u00e9s par les d\u00e9portations. Les t\u00e9moignages et le bouche \u00e0 oreille expliquent en partie ce ph\u00e9nom\u00e8ne.<\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">A titre d&rsquo;exemple de nombreux journaux tels que <i><b>Lib\u00e9ration-Sud<\/b><\/i><i>,<\/i><b> <\/b><i><b>Le Populaire<\/b><\/i><b> <\/b>ou <i><b>Franc-Tireur<\/b><\/i> publient des articles sur les rafles, d\u00e9non\u00e7ant en particulier la traque des enfants. D\u00e8s lors, &lsquo;on peut noter que la presse r\u00e9sistante participe \u00e0 un r\u00e9el effort de mobilisation des consciences en cet \u00e9t\u00e9 1942. <\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">Pourtant \u00e0 partir de l&rsquo;automne 1942, les questions de l&rsquo;internement et de la d\u00e9portation des Juifs ne semblent plus occuper les esprits. <\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">Pour analyser l&rsquo;opinion des fran\u00e7ais sous le r\u00e9gime de Vichy, il faut se replacer dans le contexte de l&rsquo;\u00e9poque. La France est occup\u00e9e par une nation \u00e9trang\u00e8re, imp\u00e9rialiste, le r\u00e9gime de Vichy est un \u00e9tat r\u00e9pressif soumis aux directives allemandes. La libert\u00e9 d&rsquo;expression est \u00e9touff\u00e9 par la propagande de l\u2019\u00c9tat, l&rsquo;id\u00e9ologie nazie et la censure de la presse, aucune opposition n&rsquo;est tol\u00e9r\u00e9e. Les Fran\u00e7ais sont partag\u00e9s entre la haine de l&rsquo;occupant et la collaboration, par crainte de r\u00e9primandes ou bien par opportunisme, les raisons sont diverses est vari\u00e9es. <\/span><\/span><\/span><\/p>\n<p align=\"justify\"><span style=\"color: #000000\"><span style=\"font-family: Arial,serif\"><span style=\"font-size: medium\">C&rsquo;est une p\u00e9riode tumultueuse ou la peur de l&rsquo;avenir se fait ressentir. Toujours \u00e9tant que les informations officielles sur les camps sont volontairement d\u00e9form\u00e9es par la presse collaborationniste et le gouvernement\u00a0<a href=\"#sdfootnote17sym\" name=\"sdfootnote17anc\"><sup>17<\/sup><\/a>. La majorit\u00e9 des Fran\u00e7ais ne peut appr\u00e9hender avec exactitude la r\u00e9alit\u00e9 des camps. Ils ne peuvent ni mesurer ni imaginer l&rsquo;\u00e9tendue du projet nazi sur une base d&rsquo;information solide. Il peut y avoir une certaine difficult\u00e9 pour la population \u00e0 dissocier la notion de prison et de camp. La minorit\u00e9 qui a connaissance des faits est r\u00e9volt\u00e9e et s&rsquo;interroge sur la destination des convois et des trains de d\u00e9port\u00e9s. D\u00e8s lors, devant le totalitarisme du gouvernement de Vichy, l&rsquo;opposition aux traitements des intern\u00e9s et des d\u00e9port\u00e9s ne peut difficilement s&rsquo;effectuer autrement que dans l&rsquo;ombre et le silence.<\/span><\/span><\/span><\/p>\n<p style=\"text-align: right\" align=\"justify\"><a href=\"http:\/\/blogs.univ-jfc.fr\/campsdusudouest\/temoignages-des-refugies-et-citoyens-francais\/\" target=\"_blank\">Lire la suite&#8230;<\/a><\/p>\n<div id=\"sdfootnote1\">\n<p><a href=\"#sdfootnote1anc\" name=\"sdfootnote1sym\">1 \u00a0<\/a>Jos\u00e9 Giral (1879-1962)\u00a0: homme politique espagnol en charge de pr\u00e9sider le gouvernement espagnol et d&rsquo;enrayer le coup d&rsquo;\u00e9tat militaire en 1936. Face \u00e0 l&rsquo;\u00e9chec, il se r\u00e9fugie d&rsquo;abord en France avant de partir au Mexique o\u00f9 il dirige de 1945 \u00e0 1947 la pr\u00e9sidence du parti r\u00e9publicain espagnol en exil.<\/p>\n<\/div>\n<div id=\"sdfootnote2\">\n<p><a href=\"#sdfootnote2anc\" name=\"sdfootnote2sym\">2 <\/a>\u00a0L\u00e9on Blum (9 avril 1872- 30 mars 1950)\u00a0: dirigeant de la section fran\u00e7aise de l&rsquo;internationale ouvri\u00e8re (SFIO). Il est chef du gouvernement fran\u00e7ais deux fois, la premi\u00e8re de 1936 \u00e0 1937 puis la seconde de mars \u00e0 avril 1937. Sous le r\u00e9gime de Vichy, Blum est d\u00e9port\u00e9 et envoy\u00e9 au camp de Buchenwald.<\/p>\n<\/div>\n<div id=\"sdfootnote3\">\n<p><a href=\"#sdfootnote3anc\" name=\"sdfootnote3sym\">3 <\/a>\u00a0Pierre Cott (20 novembre 1895- 21 ao\u00fbt 1977), promu ministre de l&rsquo;Air sous Poincar\u00e9, il cr\u00e9e en autre la compagnie nationale <i>Air France. <\/i>Il reste ministre sous Blum en 1936 et fonde la m\u00eame ann\u00e9e le rassemblement universel pour la paix. Pendant la guerre civile, il aide clandestinement les espagnols. Avant de fuir la France en 1940 et de s&rsquo;exiler en Angleterre, puis au \u00c9tat- Unis.<\/p>\n<\/div>\n<div id=\"sdfootnote4\">\n<p><a href=\"#sdfootnote4anc\" name=\"sdfootnote4sym\">4<\/a>\u00a0\u00a0<i><b>L\u2019\u00c9cho de Paris<\/b><\/i>, du 25 juillet 1936. Source: La biblioth\u00e8que universelle, Gallica (http:\/\/gallica.bnf.fr\/ark:\/12148\/bpt6k815975b.item)<\/p>\n<\/div>\n<div id=\"sdfootnote5\">\n<p><a href=\"#sdfootnote5anc\" name=\"sdfootnote5sym\">5 <\/a>\u00a0<i><b>L\u2019\u00c9cho de Paris<\/b><\/i>, du 25 juillet 1936 . <i>Source: La biblioth\u00e8que universelle, Gallica (http:\/\/gallica.bnf.fr\/ark:\/12148\/bpt6k815975b.item)<\/i><\/p>\n<\/div>\n<div id=\"sdfootnote6\">\n<p><a href=\"#sdfootnote6anc\" name=\"sdfootnote6sym\">6 <\/a>\u00a0Source: le site \u00ab\u00a024 ao\u00fbt 1944\u00a0\u00bb,<a href=\"http:\/\/www.24-aout-1944.org\/L-exode-republicain-espagnol-de\">http:\/\/www.24-aout-1944.org\/L-exode-republicain-espagnol-de<\/a> ).<\/p>\n<\/div>\n<div id=\"sdfootnote7\">\n<p align=\"justify\"><span style=\"font-family: Times New Roman,serif\"><span style=\"font-size: medium\"><i><a href=\"#sdfootnote7anc\" name=\"sdfootnote7sym\">7<\/a><span style=\"color: #000000\"><span style=\"font-size: small\">\u00a0 Le 24 ao\u00fbt 1944 <\/span><\/span><\/i><span style=\"color: #000000\"><span style=\"font-size: small\">( http:\/\/www.24-aout-1944.org\/L-exode-republicain-espagnol-de).<\/span><\/span><\/span><\/span><\/p>\n<\/div>\n<div id=\"sdfootnote8\">\n<p><span style=\"font-size: medium\"><i><a href=\"#sdfootnote8anc\" name=\"sdfootnote8sym\">8<\/a><span style=\"font-size: small\"><b>\u00a0 Le Midi Socialiste<\/b><\/span><\/i><span style=\"font-size: small\">du 19 f\u00e9vrier 1939. Source: biblioth\u00e8que num\u00e9rique de Toulouse (Rosalis)\u00a0:(http:\/\/images.midi.bibliotheque.toulouse.fr\/1939\/B315556101_MIDSOC_1939_02_19.pdf#search=\u00a0\u00bbcamps d&rsquo;argeles\u00a0\u00bb).<\/span><\/span><\/p>\n<\/div>\n<div id=\"sdfootnote9\">\n<p><span style=\"font-size: medium\"><i><a href=\"#sdfootnote9anc\" name=\"sdfootnote9sym\">9<\/a>\u00a0<span style=\"font-size: small\"><b> Le Midi Socialiste<\/b><\/span><\/i><span style=\"font-size: small\">du 19 f\u00e9vrier 1939. Source: biblioth\u00e8que num\u00e9rique de Toulouse (Rosalis)\u00a0:(http:\/\/images.midi.bibliotheque.toulouse.fr\/1939\/B315556101_MIDSOC_1939_02_19.pdf#search=\u00a0\u00bbcamps d&rsquo;argeles\u00a0\u00bb).<\/span><\/span><\/p>\n<\/div>\n<div id=\"sdfootnote10\">\n<p><span style=\"color: #000000\"><span style=\"font-family: Times New Roman,serif\"><a href=\"#sdfootnote10anc\" name=\"sdfootnote10sym\">10 \u00a0<\/a><i><b>L&rsquo;Humanit\u00e9<\/b><\/i> du 15 f\u00e9vrier 1939. (Source: la biblioth\u00e8que num\u00e9rique Gallica (http:\/\/gallica.bnf.fr\/ark:\/12148\/bpt6k407721z.item).<\/span><\/span><\/p>\n<\/div>\n<div id=\"sdfootnote11\">\n<p><a href=\"#sdfootnote11anc\" name=\"sdfootnote11sym\">11 <\/a><i><b>Ce Soir<\/b><\/i> du 12 F\u00e9vrier 1939. Source\u00a0: la biblioth\u00e8que num\u00e9rique Galllica (http:\/\/gallica.bnf.fr\/ark:\/12148\/bpt6k76364124.item).<\/p>\n<\/div>\n<div id=\"sdfootnote12\">\n<p><a href=\"#sdfootnote12anc\" name=\"sdfootnote12sym\">12 <\/a>\u00a0<i><b>Le Midi Socialiste<\/b><\/i> du 24 f\u00e9vrier 1939 ( <a href=\"https:\/\/bataillesocialiste.wordpress.com\/tag\/retirada\/\"><span style=\"font-size: small\">https:\/\/bataillesocialiste.wordpress.com\/tag\/retirada\/<\/span><\/a><span style=\"font-size: medium\">).<\/span><\/p>\n<\/div>\n<div id=\"sdfootnote13\">\n<p><span style=\"font-size: medium\"><a href=\"#sdfootnote13anc\" name=\"sdfootnote13sym\">13<\/a>\u00a0 <span style=\"font-size: small\">Source: le site <\/span><span style=\"font-size: small\"><i>\u00ab\u00a024 ao\u00fbt 1944\u00a0\u00bb\u00a0<\/i><\/span><span style=\"font-size: small\">(<a href=\"http:\/\/www.24-aout-1944.org\/L-exode-republicain-espagnol-de\">http:\/\/www.24-aout-1944.org\/L-exode-republicain-espagnol-de<\/a> ).<\/span><\/span><\/p>\n<\/div>\n<div id=\"sdfootnote14\">\n<p><a href=\"#sdfootnote14anc\" name=\"sdfootnote14sym\">14 <\/a>\u00a0<i><b>Candide<\/b><\/i>, le num\u00e9ro du 8 f\u00e9vrier 1939.<\/p>\n<\/div>\n<div id=\"sdfootnote15\">\n<p><i><a href=\"#sdfootnote15anc\" name=\"sdfootnote15sym\">15 <\/a>\u00a0Ancien membre du cabinet du ministre de l&rsquo;Int\u00e9rieur sous le r\u00e9gime de Vichy.<\/i><\/p>\n<\/div>\n<div id=\"sdfootnote16\">\n<p><i><a href=\"#sdfootnote16anc\" name=\"sdfootnote16sym\">16 <\/a>\u00a0Le Parti communiste fran\u00e7ais (PCF), parti politique fran\u00e7ais de gauche.<\/i><\/p>\n<\/div>\n<div id=\"sdfootnote17\">\n<p><a href=\"#sdfootnote17anc\" name=\"sdfootnote17sym\">17<\/a>\u00a0\u00a0<span style=\"font-family: Times New Roman,serif\"><span style=\"font-size: medium\">Source\u00a0: Denis Peschanski, <\/span><\/span><span style=\"font-family: Times New Roman,serif\"><span style=\"font-size: medium\"><i>Les camps fran\u00e7ais d&rsquo;internement(1938-1946)<\/i><\/span><\/span><span style=\"font-family: Times New Roman,serif\"><span style=\"font-size: medium\">-Doctorat d&rsquo;\u00c9tat, Histoire. Universit\u00e9 Panth\u00e9on-Sorbonne- Paris 1,2000.<\/span><\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8230; page pr\u00e9c\u00e9dente La propagande m\u00e9diatique sous le gouvernement de Daladier et le r\u00e9gime de Vichy, de 1938 \u00e0 1945 Une presse Fran\u00e7aise d\u00e9chir\u00e9e sur l&rsquo;internement des immigr\u00e9s Espagnols en 1939 La presse fran\u00e7aise commence \u00e0 parler des r\u00e9publicains espagnols &hellip; <a href=\"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/la-france-de-lentre-deux-guerres-et-de-vichy\/les-francais-et-linternement\/la-propagande-mediatique-sous-le-gouvernement-de-daladier-et-du-regime-de-vichy-de-1938-a-1945\/\">Lire la suite <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":115,"featured_media":0,"parent":16,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-json\/wp\/v2\/pages\/2043"}],"collection":[{"href":"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-json\/wp\/v2\/users\/115"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-json\/wp\/v2\/comments?post=2043"}],"version-history":[{"count":14,"href":"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-json\/wp\/v2\/pages\/2043\/revisions"}],"predecessor-version":[{"id":4226,"href":"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-json\/wp\/v2\/pages\/2043\/revisions\/4226"}],"up":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-json\/wp\/v2\/pages\/16"}],"wp:attachment":[{"href":"https:\/\/blogs.univ-jfc.fr\/campsdusudouest\/wp-json\/wp\/v2\/media?parent=2043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}