{"id":129,"date":"2023-01-01T15:54:00","date_gmt":"2023-01-01T14:54:00","guid":{"rendered":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/?p=129"},"modified":"2022-12-09T16:46:35","modified_gmt":"2022-12-09T15:46:35","slug":"solitude","status":"publish","type":"post","link":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/2023\/01\/01\/solitude\/","title":{"rendered":"Solitude"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><em>Albi, lundi apr\u00e8s-midi, <a href=\"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/?p=121\">dans une laverie<\/a><\/em><\/p>\n\n\n\n<p class=\"has-drop-cap\">Je me sens seul. Entour\u00e9 de toutes ces machines qui tournent en boucle et en boucle. Je perds la t\u00eate, je sais et je m\u2019en rends compte.<\/p>\n\n\n\n<p>Voil\u00e0 bien des jours que je poireaute ici, dans l\u2019attente d\u2019une main chaude et chaleureuse \u2013 du moins, plus que ce stupide banc glac\u00e9. J\u2019ai l\u2019espoir qu\u2019une \u00e2me charitable me prenne dans ses bras, touche mes yeux et ma bouche, me dorlote et m\u2019embarque chez elle. L\u2019adoption dont tout le monde r\u00eave. C\u2019est mon souhait le plus cher. Et pourtant, je suis encore l\u00e0, seul et abandonn\u00e9 de tous. Peut-\u00eatre que je suis trop laid et que je ne donne pas envie&nbsp;? Fais-je peur aux autres&nbsp;?<\/p>\n\n\n\n<p>Les seules mains qui m\u2019ont touch\u00e9 sont celles du monsieur du service de r\u00e9paration, une pauvre machine \u00e0 laver ne pouvait plus tourner, il m\u2019a d\u00e9cal\u00e9 pour pouvoir s\u2019asseoir durant sa pause. Ou encore celles d\u2019une dame qui ne voulait pas poser son sac par terre ni sur le banc, pestant que c\u2019est infest\u00e9 de bact\u00e9ries et que son Chanel de contrefa\u00e7on m\u00e9rite un peu plus de respect. Contrairement \u00e0 moi, a priori.<\/p>\n\n\n\n<p>J\u2019aimerais entrer dans une de ces machines, tourner et tourner, rire \u00e0 en pleurer et ressortir tout propre et tout beau. L\u2019odeur des v\u00eatements fra\u00eechement lav\u00e9s est la seule chose qui me fait tenir ici, c\u2019est r\u00e9confortant. Je me dis qu\u2019un jour, je sentirai cette odeur depuis une jolie maison ou un appartement, qu\u2019importe, tant que quelqu\u2019un prend le temps de me lire.<\/p>\n\n\n\n<p><em><a href=\"https:\/\/www.univ-jfc.fr\/culture\/latelier-decriture-jeff-champo\">OqO<\/a><\/em><\/p>\n\n\n\n<p><strong>Lisa<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Albi, lundi apr\u00e8s-midi, dans une laverie Je me sens seul. Entour\u00e9 de toutes ces machines qui tournent en boucle et en boucle. Je perds la t\u00eate, je sais et je m\u2019en rends compte. Voil\u00e0 bien des jours que je poireaute ici, dans l\u2019attente d\u2019une main chaude et chaleureuse \u2013 du moins, plus que ce stupide&hellip; <a class=\"more-link\" href=\"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/2023\/01\/01\/solitude\/\">Poursuivre la lecture <span class=\"screen-reader-text\">Solitude<\/span><\/a><\/p>\n","protected":false},"author":877,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[18,11,23],"_links":{"self":[{"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/posts\/129"}],"collection":[{"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/users\/877"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/comments?post=129"}],"version-history":[{"count":2,"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/posts\/129\/revisions"}],"predecessor-version":[{"id":132,"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/posts\/129\/revisions\/132"}],"wp:attachment":[{"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/media?parent=129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/categories?post=129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/tags?post=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}