{"id":644,"date":"2025-03-27T17:06:17","date_gmt":"2025-03-27T16:06:17","guid":{"rendered":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/?p=644"},"modified":"2025-03-27T17:06:17","modified_gmt":"2025-03-27T16:06:17","slug":"elementaire","status":"publish","type":"post","link":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/2025\/03\/27\/elementaire\/","title":{"rendered":"\u00c9l\u00e9mentaire"},"content":{"rendered":"\n<p>Le temps est comme l\u2019eau<\/p>\n\n\n\n<p>\u00c9coulement discret<\/p>\n\n\n\n<p>Constante d\u2019un ruisseau l\u00e9ger<\/p>\n\n\n\n<p>Son compte-goutte \u00e9tir\u00e9<\/p>\n\n\n\n<p>S\u2019\u00e9vapore dans un soupir achev\u00e9.<\/p>\n\n\n\n<p>Le temps est comme le feu<\/p>\n\n\n\n<p>Insoumis des heures, \u00e9clat insolent<\/p>\n\n\n\n<p>Brasier cr\u00e9pitant des souvenirs incessants<\/p>\n\n\n\n<p>Scelle en un fil d\u2019interminables instants<\/p>\n\n\n\n<p>Laisse des traces en cendres d\u2019antan.<\/p>\n\n\n\n<p>Le temps est comme l\u2019air<\/p>\n\n\n\n<p>\u00c9ternel passage qui souffle en silence<\/p>\n\n\n\n<p>T\u00e9moignages qui s\u2019\u00e9garent parfois en enfance<\/p>\n\n\n\n<p>\u00c9loigne et rapproche toujours en cadence<\/p>\n\n\n\n<p>Entrem\u00eale les jours en de vastes danses.<\/p>\n\n\n\n<p>Le temps est comme la terre<\/p>\n\n\n\n<p>Fa\u00e7onne les \u00e2mes du plus jeune \u00e0 l\u2019ancien<\/p>\n\n\n\n<p>Creuse les pas des rus\u00e9s aux incertains<\/p>\n\n\n\n<p>Conservant le dessin dans un fragile jardin<\/p>\n\n\n\n<p>Enracine ton chemin ainsi que le mien.<\/p>\n\n\n\n<p><strong>Assya<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le temps est comme l\u2019eau \u00c9coulement discret Constante d\u2019un ruisseau l\u00e9ger Son compte-goutte \u00e9tir\u00e9 S\u2019\u00e9vapore dans un soupir achev\u00e9. Le temps est comme le feu Insoumis des heures, \u00e9clat insolent Brasier cr\u00e9pitant des souvenirs incessants Scelle en un fil d\u2019interminables instants Laisse des traces en cendres d\u2019antan. Le temps est comme l\u2019air \u00c9ternel passage qui&hellip; <a class=\"more-link\" href=\"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/2025\/03\/27\/elementaire\/\">Poursuivre la lecture <span class=\"screen-reader-text\">\u00c9l\u00e9mentaire<\/span><\/a><\/p>\n","protected":false},"author":877,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[43],"tags":[124,53],"_links":{"self":[{"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/posts\/644"}],"collection":[{"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/users\/877"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/comments?post=644"}],"version-history":[{"count":1,"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/posts\/644\/revisions"}],"predecessor-version":[{"id":645,"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/posts\/644\/revisions\/645"}],"wp:attachment":[{"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/media?parent=644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/categories?post=644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/jeffchampo\/wp-json\/wp\/v2\/tags?post=644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}