{"id":37,"date":"2013-05-08T18:45:57","date_gmt":"2013-05-08T16:45:57","guid":{"rendered":"http:\/\/blogs.univ-jfc.fr\/papyrus\/voyage-culinaire-lirmik-helvasi\/"},"modified":"2017-05-05T11:41:48","modified_gmt":"2017-05-05T09:41:48","slug":"voyage-culinaire-lirmik-helvasi","status":"publish","type":"post","link":"https:\/\/blogs.univ-jfc.fr\/papyrus\/2013\/05\/08\/voyage-culinaire-lirmik-helvasi\/","title":{"rendered":"Voyage culinaire : l&rsquo;Irmik Helvasi"},"content":{"rendered":"<p>Continuons notre voyage culinaire, apr\u00e8s l&rsquo;Am\u00e9rique du sud faisons un arr\u00eat en Turquie !  Et le plat du jour est l&rsquo;Irmik Helvasi qui est un dessert Turc \u00e0 la semoule.<\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<p>Continuons notre voyage culinaire, apr\u00e8s l&rsquo;Am\u00e9rique du sud faisons un arr\u00eat en Turquie !  Et le plat du jour est l&rsquo;Irmik Helvasi qui est un dessert Turc \u00e0 la semoule.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ingr\u00e9dients :<\/strong><\/p>\n<p>&#8211; une grosse poign\u00e9e de pignons de pin<\/p>\n<p>&#8211; 2 verres de sucre<\/p>\n<p>&#8211; 160 g de beurre<\/p>\n<p>&#8211; 4 verres de lait<\/p>\n<p>&#8211; 1 verre et demi de semoule fine<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pr\u00e9paration : <\/strong><\/p>\n<p>Mettez le beurre \u00e0 fondre dans une grande po\u00eale avec les pignons de pin. Une fois que le beurre est fondu, ajoutez la semoule et laissez cuire jusqu&rsquo;\u00e0 ce que le m\u00e9lange prenne une couleur dor\u00e9e (environ 15 min) sur feu moyen sans cesser de remuer.<\/p>\n<p>Ajoutez ensuite le lait et le sucre et remuez le tout. Couvrez la po\u00eale et laissez cuire jusqu&rsquo;\u00e0 ce que la semoule soit bien cuite. Mettez le tout dans un ramequin pour lui donner sa forme et ajoutez de la poudre de pistache sur le dessus.<\/p>\n<p>&nbsp;<\/p>\n<p>Afiyet olsun !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continuons notre voyage culinaire, apr\u00e8s l&rsquo;Am\u00e9rique du sud faisons un arr\u00eat en Turquie ! Et le plat du jour est l&rsquo;Irmik Helvasi qui est un dessert Turc \u00e0 la semoule. &nbsp;<\/p>\n","protected":false},"author":305,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[2],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/posts\/37"}],"collection":[{"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/comments?post=37"}],"version-history":[{"count":1,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/posts\/37\/revisions"}],"predecessor-version":[{"id":263,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/posts\/37\/revisions\/263"}],"wp:attachment":[{"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/media?parent=37"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/categories?post=37"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/tags?post=37"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}