{"id":60,"date":"2014-01-24T14:16:15","date_gmt":"2014-01-24T13:16:15","guid":{"rendered":"http:\/\/blogs.univ-jfc.fr\/papyrus\/sit-back-relax\/"},"modified":"2017-05-05T11:42:04","modified_gmt":"2017-05-05T09:42:04","slug":"sit-back-relax","status":"publish","type":"post","link":"https:\/\/blogs.univ-jfc.fr\/papyrus\/2014\/01\/24\/sit-back-relax\/","title":{"rendered":"Sit back &#038; relax"},"content":{"rendered":"<p>En Stage depuis le lundi 13 janvier , j&rsquo;ai eu l&rsquo;opportunit\u00e9 d&rsquo;\u00eatre g\u00e9n\u00e9reusement accueilli dans le service communication de la facult\u00e9 Champollion  d&rsquo;Albi ..&nbsp;.<\/p>\n<p><!--more--><\/p>\n<p>En Stage depuis le lundi 13 janvier , j&rsquo;ai eu l&rsquo;opportunit\u00e9 d&rsquo;\u00eatre g\u00e9n\u00e9reusement accueilli dans le service communication de la facult\u00e9 Champollion  d&rsquo;Albi ..&nbsp;.<\/p>\n<p>Passionn\u00e9 de musique depuis mon plus jeune \u00e2ge  et suite \u00e0 une proposition d&rsquo;article que je ne pouvais  personnellement pas refuser, voici donc une s\u00e9lection de titres (Bossa Nova&nbsp;\/Latinjazz\/Soul&nbsp;\/Funk \/Lounge ~ )  sur lesquelles vous pourriez &lsquo; Sit back &amp; relax &lsquo; apr\u00e8s une journ\u00e9e de travail bien remplis  &#8230; Titres qui vous seront , qui sait&nbsp;? Peut- \u00eatre familier &#8230;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Stage depuis le lundi 13 janvier , j&rsquo;ai eu l&rsquo;opportunit\u00e9 d&rsquo;\u00eatre g\u00e9n\u00e9reusement accueilli dans le service communication de la facult\u00e9 Champollion d&rsquo;Albi ..&nbsp;.<\/p>\n","protected":false},"author":305,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/posts\/60"}],"collection":[{"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/comments?post=60"}],"version-history":[{"count":1,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/posts\/60\/revisions"}],"predecessor-version":[{"id":253,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/posts\/60\/revisions\/253"}],"wp:attachment":[{"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/media?parent=60"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/categories?post=60"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/tags?post=60"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}