{"id":64,"date":"2014-03-13T15:29:15","date_gmt":"2014-03-13T14:29:15","guid":{"rendered":"http:\/\/blogs.univ-jfc.fr\/papyrus\/champo-seduit-les-jeunes\/"},"modified":"2017-05-05T12:00:06","modified_gmt":"2017-05-05T10:00:06","slug":"champo-seduit-les-jeunes","status":"publish","type":"post","link":"https:\/\/blogs.univ-jfc.fr\/papyrus\/2014\/03\/13\/champo-seduit-les-jeunes\/","title":{"rendered":"Champo s\u00e9duit les jeunes"},"content":{"rendered":"<p>Ce Mercredi 13 f\u00e9vrier 2014, les \u00e9tudiants de Champollion ont pu voir d\u00e9barquer une multitude de lyc\u00e9ens en qu\u00eate de r\u00e9ponses pour leurs avenirs. Tous \u00e9taient heureux de pouvoir enfin rentrer dans la cours des grands qui sera peut \u00eatre l&rsquo;ann\u00e9e prochaine, leur nouvelle terre d&rsquo;accueil.<br \/>\n<!--more--><\/p>\n<p>Ce Mercredi 13 f\u00e9vrier 2014, les \u00e9tudiants de Champollion ont pu voir d\u00e9barquer une multitude de lyc\u00e9ens en qu\u00eate de r\u00e9ponses pour leurs avenirs. Tous \u00e9taient heureux de pouvoir enfin rentrer dans la cours des grands qui sera peut \u00eatre l&rsquo;ann\u00e9e prochaine, leur nouvelle terre d&rsquo;accueil. <!--break--><\/p>\n<p>Toute l&rsquo;apr\u00e8s-midi, les potentielles nouvelles recrus, accompagn\u00e9s souvent par leurs parents mais aussi par quelques \u00e9tudiants d\u00e9vou\u00e9, ont eu l&rsquo;occasion de d\u00e9couvrir notre petit mais pas moins  excellent domaine  universitaire. Dans une ambiance visiblement d\u00e9contract\u00e9, sous un soleil magnifique, les groupes ce sont succ\u00e9d\u00e9s, posant mille et une question aux \u00e9tudiants, reconvertis guide pour l&rsquo;occasion.<\/p>\n<p>No\u00e9mie est \u00e9tudiante en premi\u00e8re ann\u00e9e d&rsquo;espagnol \u00e0 Champollion et pour elle, il \u00e9tait \u00e9vident de participer \u00e0 cette journ\u00e9e. \u00ab J&rsquo;ai \u00e9t\u00e9 dans leurs situation l&rsquo;ann\u00e9e derni\u00e8re et j&rsquo;avais vraiment appr\u00e9ci\u00e9 que les \u00e9tudiants soient attentifs aux questions alors j&rsquo;ai fais de m\u00eame avec eux\u00bb. Apr\u00e8s cet journ\u00e9e, les lyc\u00e9ens \u00e9taient, pour la  majorit\u00e9 conquis par Champollion. \u00ab&nbsp;Ils \u00e9taient tous excit\u00e9s de voir la fac et ils nous ont tous remerci\u00e9 pour l&rsquo;accueil chaleureux donc je suis compl\u00e8tement satisfaite.&nbsp;\u00bb<\/p>\n<p>Benjamin, 18 ans en Terminale ES originaire de l&rsquo;Aveyron \u00e9tait quant a lui satisfait et plut\u00f4t excit\u00e9 \u00e0 l&rsquo;id\u00e9e de venir ici. \u00ab&nbsp; J&rsquo;ai pas encore le bac en poche mais franchement, j&rsquo;ai h\u00e2te de m&rsquo;installer sur Albi et de vivre enfin ma vie d&rsquo;\u00e9tudiant&nbsp;\u00bb.<\/p>\n<p>Incontestablement, la fac attire toujours autant les jeunes bacheliers. Avec ses 3650 \u00e9tudiants inscris et une hausse de 7% en 2013, le CUFR a de quoi \u00eatre rassur\u00e9 quant \u00e0 son cru 2014. Champollion plait, parole d&rsquo;\u00e9tudiant.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce Mercredi 13 f\u00e9vrier 2014, les \u00e9tudiants de Champollion ont pu voir d\u00e9barquer une multitude de lyc\u00e9ens en qu\u00eate de r\u00e9ponses pour leurs avenirs. Tous \u00e9taient heureux de pouvoir enfin rentrer dans la cours des grands qui sera peut \u00eatre l&rsquo;ann\u00e9e prochaine, leur nouvelle terre d&rsquo;accueil.<\/p>\n","protected":false},"author":305,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,6],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/posts\/64"}],"collection":[{"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/users\/305"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/comments?post=64"}],"version-history":[{"count":1,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/posts\/64\/revisions"}],"predecessor-version":[{"id":205,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/posts\/64\/revisions\/205"}],"wp:attachment":[{"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/media?parent=64"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/categories?post=64"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/papyrus\/wp-json\/wp\/v2\/tags?post=64"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}