{"id":10799,"date":"2022-02-24T11:59:21","date_gmt":"2022-02-24T10:59:21","guid":{"rendered":"http:\/\/blogs.univ-jfc.fr\/vphn\/?p=10799"},"modified":"2022-03-13T15:22:00","modified_gmt":"2022-03-13T14:22:00","slug":"la-vicomte-de-lautrec-2022","status":"publish","type":"post","link":"https:\/\/blogs.univ-jfc.fr\/vphn\/2022\/02\/24\/la-vicomte-de-lautrec-2022\/","title":{"rendered":"La vicomt\u00e9 de Lautrec [2022]"},"content":{"rendered":"<p align=\"justify\">Au Moyen-\u00c2ge, de profonds changements politiques, culturels ou religieux ont lieu dans le Languedoc. Une cit\u00e9 du nom de Lautrec s\u2019affirme et se retrouve au premier plan dans la g\u00e9opolitique du Midi. La vicomt\u00e9 de Lautrec de par sa position strat\u00e9gique dans la r\u00e9gion mais aussi de par des strat\u00e9gies matrimoniales ou religieuses, occupe une place importante dans la diplomatie languedocienne. A la t\u00eate de la vicomt\u00e9, la famille des de Lautrec parvient \u00e0 s\u2019imposer au milieu de deux familles puissantes, les Raimondins de Toulouse et les Trencavel de Carcassonne. La vicomt\u00e9 pendant plus de quatre si\u00e8cles, de sa cr\u00e9ation en 989 jusqu&rsquo;\u00e0 son rattachement au domaine royal en 1338, se retrouve au c\u0153ur des changements qui ont lieu dans le Languedoc de la p\u00e9riode f\u00e9odale.\u00a0<\/p>\n\n\n<p class=\"has-text-align-center\">Il est possible de se demander si la famille vicomtale des de Lautrec arrive \u00e0 s\u2019ancrer dans un territoire leur&nbsp; permettant d\u2019\u00e9merger comme puissance politique r\u00e9gionale dans le contexte f\u00e9odal particulier du Languedoc.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"has-text-align-center\">L\u2019origine de la famille des De Lautrec&nbsp;<\/h3>\n\n\n<p align=\"justify\"> A l\u2019origine, la vicomt\u00e9 de Lautrec \u00e9tait administr\u00e9e par une viguerie carolingienne, c\u2019est-\u00e0-dire une juridiction administrative exerc\u00e9e par un repr\u00e9sentant local du pouvoir royal. Ces repr\u00e9sentants du pouvoir royal \u00e9taient appel\u00e9s des<a rel=\"noreferrer noopener\" href=\"https:\/\/cnrtl.fr\/definition\/missi%20dominici\" target=\"_blank\"> <em>missi dominici<\/em><\/a><em>.<\/em> Au cours du X\u00e8me si\u00e8cle un<a href=\"http:\/\/passerelles.bnf.fr\/dossier\/chateau_a_motte_01.php\" target=\"_blank\" rel=\"noreferrer noopener\"> syst\u00e8me f\u00e9odal<\/a> se met en place progressivement dans le territoire. En effet, le pouvoir se recentre autour de familles.<\/p>\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/02\/Genealogie-Xieme-3.png\" alt=\"\" class=\"wp-image-11007\" width=\"307\" height=\"295\" srcset=\"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/02\/Genealogie-Xieme-3.png 579w, https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/02\/Genealogie-Xieme-3-300x289.png 300w\" sizes=\"(max-width: 307px) 100vw, 307px\" \/><figcaption><a rel=\"noreferrer noopener\" href=\"https:\/\/www.persee.fr\/doc\/anami_0003-4398_2002_num_114_239_2777\" target=\"_blank\">Esquisse g\u00e9n\u00e9alogie des De Lautrec du Xe au XIe si\u00e8cle par Zalmen Ben-Nathan<\/a><\/figcaption><\/figure><\/div>\n\n\n<p align=\"justify\">La famille des Lautrec s\u2019installe dans la vicomt\u00e9 dans la premi\u00e8re moiti\u00e9 du X\u00e8me si\u00e8cle lorsque Bernard Ier devient<em> missi dominici<\/em> du territoire. Il est vicaire et avou\u00e9 du comte de Toulouse \u00e0 partir de 918. A sa mort, il partage ses \u00e9tats entre ses deux fils : Aton I et Sicard I. Aton Ier est la souche de la famille <a href=\"https:\/\/www.carcassonne.org\/article-page\/famille-de-trencavel\" target=\"_blank\" rel=\"noreferrer noopener\">Trencavel<\/a> ; il obtient la partie septentrionale, ce qui va former la vicomt\u00e9 d\u2019Albi. Son fr\u00e8re, Sicard Ier, obtient la partie m\u00e9ridionale qui f\u00fbt d\u00e9sign\u00e9e comme vicomt\u00e9 de Lautrec. C\u2019est donc \u00e0 partir de Sicard Ier que la vicomt\u00e9 est administr\u00e9e par la famille de Lautrec<\/p>\n\n\n<p>                                                                                                               <\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"has-text-align-center\"><em>L\u2019influence des de Lautrec dans la g\u00e9opolitique du Languedoc (1080-1209)<\/em><\/h3>\n\n\n<p align=\"justify\">La famille des de Lautrec parvient \u00e0 se lier avec de puissantes familles voisines \u00e0 la mani\u00e8re du mariage entre Sicard V et Ad\u00e9la\u00efde Trencavel ou le suppos\u00e9 mariage d\u2019un membre de la famille de Lautrec, \u00e0 Alix, l\u2019une des filles du comte de Toulouse. Ainsi, la vicomt\u00e9 de Lautrec prend largement en puissance au cours du XII si\u00e8cle.&nbsp;<\/p>\n<p align=\"justify\">Elle prend de l\u2019importance sur deux plans bien distincts: son r\u00f4le dans la g\u00e9opolitique du Languedoc et son importance sur le pouvoir spirituel. Elle a d\u00e9sormais un poids important dans la g\u00e9opolitique r\u00e9gionale. En effet, elle contracte des alliances avec de puissants nobles (Trencavel, Raimondins), a la capacit\u00e9 d\u2019intervenir dans des conflits arm\u00e9s et m\u00eame d\u2019en \u00eatre les m\u00e9diateurs. En effet, Sicard IV affronte les Trencavel d\u00e8s 1141, pourtant la vicomt\u00e9 tente d\u2019apaiser la situation entre les Raimondins et les Trencavel seulement trois ans plus tard. Autre \u00e9l\u00e9ment marquant de la puissance des vicomtes au XII si\u00e8cle, les de Lautrec joue un r\u00f4le important dans <a href=\"https:\/\/www.persee.fr\/doc\/cafan_0575-061x_1969_act_4_1_964\" target=\"_blank\" rel=\"noreferrer noopener\">la convention d\u2019Albi<\/a> de 1191, pour \u00e9tablir une paix entre les seigneurs albigeois&nbsp; dans une atmosph\u00e8re de fortes tensions.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/02\/VIELMUR_Tour-des-Lautrec_1.jpg\" alt=\"\" class=\"wp-image-10952\" width=\"287\" height=\"333\" srcset=\"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/02\/VIELMUR_Tour-des-Lautrec_1.jpg 537w, https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/02\/VIELMUR_Tour-des-Lautrec_1-259x300.jpg 259w\" sizes=\"(max-width: 287px) 100vw, 287px\" \/><figcaption><a href=\"https:\/\/www.hades-archeologie.com\/operation\/la-tour-des-lautrec\/#&amp;gid=1&amp;pid=1\" target=\"_blank\" rel=\"noreferrer noopener\">Emplacement de la Tour des Lautrec  dans l&rsquo;abbaye b\u00e9n\u00e9dictine de Vielmur. <\/a><\/figcaption><\/figure><\/div>\n\n\n<p align=\"justify\">Sur le plan religieux, la vicomt\u00e9 d\u00e9veloppe une grande influence. En effet, les vicomtes construisent des abbayes \u00e0 la mani\u00e8re de celle de Vielmur, \u00e0 la t\u00eate desquelles, ils placent des membres de leur famille. Mais le pouvoir spirituel de la vicomt\u00e9 ne s\u2019\u00e9tend pas seulement \u00e0 un niveau local, mais aussi r\u00e9gional avec le placement de certains fils de vicomte, au poste d\u2019\u00e9v\u00eaque, tel Frotard II, \u00e9v\u00eaque d\u2019Albi de 1062 \u00e0 1083. Signe de leur pouvoir spirituel, leur invitation au <a href=\"https:\/\/books.openedition.org\/pumi\/26633?lang=fr\">c<\/a><a href=\"https:\/\/books.openedition.org\/pumi\/26633?lang=fr\" target=\"_blank\" rel=\"noreferrer noopener\">oncile de Lombers<\/a> en 1165 pour tenter de mettre fin \u00e0 l\u2019h\u00e9r\u00e9sie qui se d\u00e9veloppe dans le Languedoc: le catharisme.&nbsp;<\/p>\n<p align=\"justify\">L\u2019institution eccl\u00e9siastique est alors primordiale pour la famille, elle utilise ces investitures pour accro\u00eetre son influence. En effet, les postes religieux&nbsp; poss\u00e9d\u00e9s par les De Lautrec ont \u00e9galement un aspect politique qui permet \u00e0 la vicomt\u00e9 de consolider leur&nbsp; pouvoir et leur&nbsp; influence dans la r\u00e9gion.<\/p>\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"has-text-align-center\"><em>La croisade contre les cathares (1209-1229)&nbsp;<\/em><\/h3>\n\n\n<p align=\"justify\"> <a rel=\"noreferrer noopener\" href=\"https:\/\/www.worldhistory.org\/trans\/fr\/1-17485\/la-croisade-des-albigeois\/\" target=\"_blank\">La croisade Albigeoise <\/a>(1209-1229) marque un v\u00e9ritable tournant dans la g\u00e9opolitique du Languedoc. <a href=\"https:\/\/www.mairie-albi.fr\/fr\/le-catharisme\">L\u2019h\u00e9r\u00e9sie cathare<\/a>  qui s\u2019est d\u00e9velopp\u00e9e dans le Languedoc est fortement condamn\u00e9e par la papaut\u00e9 qui lance alors la croisade albigeoise. Une guerre \u00e9clate entre les seigneurs septentrionaux qui combattent cette h\u00e9r\u00e9sie et certains des grands seigneurs languedociens&nbsp; qui prennent les armes pour d\u00e9fendre leur territoire et les populations cathares.&nbsp;<\/p>\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/02\/Capture-1.png\" alt=\"\" class=\"wp-image-10953\" width=\"321\" height=\"233\" srcset=\"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/02\/Capture-1.png 508w, https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/02\/Capture-1-300x217.png 300w\" sizes=\"(max-width: 321px) 100vw, 321px\" \/><figcaption><a href=\"https:\/\/www.persee.fr\/doc\/anami_0003-4398_2002_num_114_239_2777\" target=\"_blank\" rel=\"noreferrer noopener\">Esquisse g\u00e9n\u00e9alogie des De Lautrec du XIIe au XIIIe si\u00e8cle par Zalmen Ben-Nathan<\/a><\/figcaption><\/figure><\/div>\n\n\n<p align=\"justify\">La vicomt\u00e9 de Lautrec adopte une politique diff\u00e9rente durant cette croisade. En effet les deux fr\u00e8res, Sicard VI et Bertrand Ier, alors \u00e0 la t\u00eate de la vicomt\u00e9, ne d\u00e9fendent pas le m\u00eame camp. Sicard VI, \u00e9pouse Agn\u00e8s Mauvoisin, parente de Bouchard Marly, un&nbsp; lieutenant de Simon de Montfort (chef de file des crois\u00e9s). Il soutient dans un premier temps la croisade. Bertrand Ier lui se rallie aux c\u00f4t\u00e9s des grands seigneurs languedociens consid\u00e9rant la croisade comme une agression \u00e0 ses pr\u00e9rogatives seigneuriales. Ainsi les vicomtes de Lautrec jouent un r\u00f4le politique diff\u00e9renci\u00e9 se trouvant&nbsp; dans les deux camps rivaux lors de la croisade.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/02\/Gravure.png\" alt=\"\" class=\"wp-image-10955\" width=\"417\" height=\"273\" srcset=\"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/02\/Gravure.png 844w, https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/02\/Gravure-300x196.png 300w, https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/02\/Gravure-768x502.png 768w\" sizes=\"(max-width: 417px) 100vw, 417px\" \/><figcaption><a href=\"https:\/\/www.herodote.net\/La_croisade_contre_les_Albigeois-synthese-98.php\" target=\"_blank\" rel=\"noreferrer noopener\">Le pape Innocent III excommunie les Albigeois (\u00e0 gauche), Simon de Montfort (\u00e0 droite) (miniature, Grandes Chroniques de France, XIVe si\u00e8cle, British Library, Londres)<\/a><br><\/figcaption><\/figure><\/div>\n\n\n<p align=\"justify\">Apr\u00e8s les victoires du comte de Toulouse sur l\u2019arm\u00e9e crois\u00e9e (1224), Sicard VI d\u00e9cide de changer de camp et soutient lui aussi les seigneurs languedociens. Il continue de les soutenir m\u00eame lorsque le roi Louis VIII prend part \u00e0 la croisade en 1226. Le trait\u00e9 de Meaux en 1229 marque la fin de la croisade, les seigneurs du Languedoc sont d\u00e9faits. Sicard VI gr\u00e2ce \u00e0 ses relations avec les crois\u00e9s parvient \u00e0 garder ses terres, alors que son fr\u00e8re Bertrand Ier a d\u00fb attendre 1235, pour pouvoir retrouver sa part de la vicomt\u00e9. Ainsi le redimensionnement politique du Languedoc apr\u00e8s la croisade albigeoise a peu d\u2019effet sur la vicomt\u00e9 de Lautrec. Ainsi la souplesse politique des vicomtes permet \u00e0 la maison de ne pas \u00eatre d\u00e9poss\u00e9d\u00e9e, compar\u00e9e \u00e0 d\u2019autres maisons comme les Trencavel ou les de Minerve, qui suite \u00e0 la croisade perdent la totalit\u00e9 de leur fief. N\u00e9anmoins progressivement la vicomt\u00e9 est entour\u00e9e de seigneurs \u00e9trangers comme les de Monfort de Castres.&nbsp;<\/p>\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"has-text-align-center\"><em>Un territoire imposant perdant de son influence (1280-1338)<\/em><\/h3>\n\n\n<p align=\"justify\">Suite \u00e0 la croisade albigeoise qui redimensionne et entra\u00eene une profonde mutation politique du Languedoc, les vicomtes Lautr\u00e9cois arrivent tout de m\u00eame \u00e0 se maintenir dans le jeu politique. En effet, les vicomtes r\u00e9ussissent gr\u00e2ce \u00e0 des politiques matrimoniales \u00e0 agrandir leur territoire et leur privil\u00e8ge dans la r\u00e9gion. Le territoire atteint son apog\u00e9e&nbsp; en 1306 avec le mariage de B\u00e9atrix II de Lautrec au vicomte de Lomagne, Bertrand de Got. La vicomt\u00e9 Lautr\u00e9coise a&nbsp; alors sous son contr\u00f4le&nbsp; tout le territoire entre les rives sud du Tarn, du Thor\u00e9, de l\u2019Agout, de la Montagne Noire jusqu&rsquo;\u00e0 Puylaurens et \u00e0 la limite du Lauragais du Nord.&nbsp;<\/p>\n<p align=\"justify\"><\/p>\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" src=\"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/03\/lomagne-1-edited.png\" alt=\"\" class=\"wp-image-11257\" width=\"464\" height=\"397.1457975986278\" srcset=\"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/03\/lomagne-1-edited.png 389w, https:\/\/blogs.univ-jfc.fr\/vphn\/wp-content\/uploads\/sites\/65\/2022\/03\/lomagne-1-edited-300x256.png 300w\" sizes=\"(max-width: 389px) 100vw, 389px\" \/><figcaption><span class=\"has-inline-color has-white-color\">Reg<em>roupement territorial des principaut\u00e9s du Sud-Ouest et du Languedoc aquitains en 1306 &#8211;  source:  Zalmen Ben-Nathan Philippe, La vicomt\u00e9 de Lautrec au Moyen \u00e2ge: seigneurs, bourgeois et paysans en Albigeois, GERALH, 2011<\/em><\/span><br><\/figcaption><\/figure>\n\n\n<p align=\"justify\">Mais, 1306 marque une rupture dans l&rsquo;accroissement de l\u2019influence lautr\u00e9coise. L&rsquo;immixtion royale affaiblit le pouvoir vicomtal. La multiplicit\u00e9 de vicomte par le r\u00e9gime de&nbsp; cod\u00e9tention de la vicomt\u00e9 entra\u00eene une baisse de la coh\u00e9sion vicomtale, ce qui permet au&nbsp; roi de France <a href=\"https:\/\/www.larousse.fr\/encyclopedie\/personnage\/Philippe_IV_le_Bel\/137969\" target=\"_blank\" rel=\"noreferrer noopener\">Philippe le Bel<\/a>, d&rsquo;acheter la moiti\u00e9 de la vicomt\u00e9 de Lautrec. Le pouvoir royal s&rsquo;int\u00e9resse alors au positionnement de&nbsp; la vicomt\u00e9 de Lautrec,&nbsp; pour son placement strat\u00e9gique dans le dispositif&nbsp; d\u00e9fensif&nbsp; du Carcassonnais. Ainsi, la maison des De Lautrec et le roi de France cod\u00e9tiennent la vicomt\u00e9 jusqu\u2019en 1338, o\u00f9 la part des vicomtes se trouve \u00eatre spoli\u00e9e par le roi&nbsp; au profit du comte de Foix.<\/p>\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<h3 class=\"has-text-align-left\"><em>Conclusion<\/em><\/h3>\n\n\n<p align=\"justify\">Durant quatre si\u00e8cles, la vicomt\u00e9 lautr\u00e9coise f\u00fbt au centre des d\u00e9veloppements \u00e9conomiques, religieux et politiques du Languedoc. Venant d\u2019une famille ancienne languedocienne, elle \u00e9merge dans le contexte de&nbsp; la&nbsp; mutation f\u00e9odale&nbsp; du Xe si\u00e8cle. La famille s\u2019ancre ainsi dans un territoire au centre de nombreuses entit\u00e9s politiques, profitant ainsi des nombreux leviers g\u00e9opolitiques que leur placement g\u00e9ographique offre. Les&nbsp; Lautrec utilisent ainsi de nombreuses strat\u00e9gies pour accro\u00eetre leur influence et leur richesse avec des alliances matrimoniales, des prises d\u2019investiture religieuse, des alliances politiques et des arbitrages dans diff\u00e9rents conflits importants du Languedoc. Malgr\u00e9 la croisade albigeoise du XIIIe si\u00e8cle, la famille arrive \u00e0 se maintenir \u00e0 la t\u00eate de la vicomt\u00e9 et parvient m\u00eame \u00e0 accro\u00eetre leur influence et leur territoire dans la sph\u00e8re r\u00e9gionale.&nbsp; La vicomt\u00e9 conna\u00eet durant la premi\u00e8re moiti\u00e9 du XIVe un profond affaiblissement dans son fonctionnement structurel qui permet&nbsp; l&rsquo;immixtion de la royaut\u00e9 et l&rsquo;assimilation des pr\u00e9rogatives vicomtales, mettant progressivement fin \u00e0 l\u2019ind\u00e9pendance de ces vicomtes en 1338.<\/p>\n\n\n<div class=\"wp-block-buttons alignleft\">\n<div class=\"wp-block-button is-style-fill\"><a class=\"wp-block-button__link has-light-green-cyan-background-color has-text-color has-background\" href=\"https:\/\/blogs.univ-jfc.fr\/vphn\/2022\/02\/24\/bibliographie-la-vicomte-de-lautrec\/\" style=\"border-radius:47px;color:#fffffa\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>Bibliographie : La vicomt\u00e9 de Lautrec<\/em><\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p>                                                                                                                                                                                                                      <\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">.<\/p>\n\n\n\n<p class=\"has-black-color has-text-color\">.<\/p>\n\n\n\n<p>L2:  Bigorre Marie &#8211; Four\u00e8s Mathis                       <\/p>\n\n\n\n<p>L1: Nonorgues Sarah &#8211; Oulmi\u00e8re Quentin- Lajoinie Lina &#8211; Delon Mothes Robin &#8211; Salvan Marc<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au Moyen-\u00c2ge, de profonds changements politiques, culturels ou religieux ont lieu dans le Languedoc. Une cit\u00e9 du nom de Lautrec s\u2019affirme et se retrouve au premier plan dans la g\u00e9opolitique du Midi. La vicomt\u00e9 de Lautrec de par sa position strat\u00e9gique dans la r\u00e9gion mais aussi de par des strat\u00e9gies matrimoniales ou religieuses, occupe une &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/blogs.univ-jfc.fr\/vphn\/2022\/02\/24\/la-vicomte-de-lautrec-2022\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;La vicomt\u00e9 de Lautrec [2022]&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":855,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[],"tags":[],"_links":{"self":[{"href":"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-json\/wp\/v2\/posts\/10799"}],"collection":[{"href":"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-json\/wp\/v2\/users\/855"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-json\/wp\/v2\/comments?post=10799"}],"version-history":[{"count":47,"href":"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-json\/wp\/v2\/posts\/10799\/revisions"}],"predecessor-version":[{"id":11369,"href":"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-json\/wp\/v2\/posts\/10799\/revisions\/11369"}],"wp:attachment":[{"href":"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-json\/wp\/v2\/media?parent=10799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-json\/wp\/v2\/categories?post=10799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.univ-jfc.fr\/vphn\/wp-json\/wp\/v2\/tags?post=10799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}